{"id":464,"date":"2025-07-29T06:54:05","date_gmt":"2025-07-29T06:54:05","guid":{"rendered":"https:\/\/wetron.es\/blog\/?p=464"},"modified":"2025-07-29T06:55:36","modified_gmt":"2025-07-29T06:55:36","slug":"un-afterwork-de-verano-con-mucha-punteria","status":"publish","type":"post","link":"https:\/\/wetron.es\/blog\/index.php\/2025\/07\/29\/un-afterwork-de-verano-con-mucha-punteria\/","title":{"rendered":"Un Afterwork de verano con mucha punter\u00eda"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"464\" class=\"elementor elementor-464\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ce4c8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ce4c8a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59e6228\" data-id=\"59e6228\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3261adf elementor-widget elementor-widget-heading\" data-id=\"3261adf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 []\"><strong data-prosemirror-content-type=\"mark\" data-prosemirror-mark-name=\"strong\">Un Afterwork de verano con mucha punter\u00eda<\/strong><\/p><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f992c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f992c9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eaf1283\" data-id=\"eaf1283\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-046b1d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"046b1d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c65c555\" data-id=\"c65c555\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-138e264 elementor-widget elementor-widget-spacer\" data-id=\"138e264\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e66364d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e66364d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf626ed\" data-id=\"bf626ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2d50c9 elementor-widget elementor-widget-text-editor\" data-id=\"d2d50c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>El pasado jueves 24 de julio <\/strong>celebramos en WETRON nuestro <strong data-renderer-mark=\"true\">afterwork de verano<\/strong>, una cita pensada para desconectar, disfrutar y reforzar los lazos entre compa\u00f1eros m\u00e1s all\u00e1 del entorno laboral. Tambi\u00e9n un <strong>punto de inflexi\u00f3n antes de la famosa \u00abparada de verano\u00bb de muchos de nuestros clientes<\/strong>. Estos se toman un descanso mientras nosotros buscamos implantar las mejoras de las instalaciones de producci\u00f3n que se han planificado y preparado conscientemente. Cuando nuestros clientes vuelven de la parada, las l\u00edneas funcionan de nuevo con normalidad y con las mejoras incorporadas.<\/p><p data-renderer-start-pos=\"266\">En el evento nos reunimos cerca de <strong data-renderer-mark=\"true\">40 personas de WETRON Iberica <\/strong>en una <strong data-renderer-mark=\"true\">bolera. D<\/strong>iferentes <strong>equipos se retaron a unas rondas divertidas de bolos, acompa\u00f1adas de <\/strong><strong data-renderer-mark=\"true\">refrescos, tapas<\/strong><strong> y muchas risas<\/strong>. Fue una tarde distendida, marcada por el buen humor y el compa\u00f1erismo que caracteriza nuestro d\u00eda a d\u00eda.<\/p><p data-renderer-start-pos=\"570\">Al final del encuentro, <strong data-renderer-mark=\"true\">la empresa obsequi\u00f3, a todos los asistentes, con un peque\u00f1o detalle<\/strong> <strong>como muestra de agradecimiento<\/strong> por su participaci\u00f3n y el compromiso demostrado. La jornada se alarg\u00f3 hasta pasadas las 20h, entre charlas, bromas y muchas ganas de seguir compartiendo momentos como este.<\/p><p data-renderer-start-pos=\"570\">\u00a0<\/p><p>A quienes form\u00e1is parte de esta familia, gracias por seguir construyendo este ambiente d\u00eda a d\u00eda.<\/p><p data-renderer-start-pos=\"570\">Y a qui\u00e9n a\u00fan no nos conoce\u2026 \u00bfte imaginas trabajando en un equipo as\u00ed?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50c75b4 elementor-widget elementor-widget-image-gallery\" data-id=\"50c75b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-464 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50c75b4\" data-elementor-lightbox-title=\"20250724-9\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDY2LCJ1cmwiOiJodHRwczpcL1wvd2V0cm9uLmVzXC9ibG9nXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wN1wvMjAyNTA3MjQtOS5qcGciLCJzbGlkZXNob3ciOiI1MGM3NWI0In0%3D\" href='https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-9.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-9-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-9-200x300.jpg 200w, https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-9.jpg 667w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50c75b4\" data-elementor-lightbox-title=\"20250724-15\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDY3LCJ1cmwiOiJodHRwczpcL1wvd2V0cm9uLmVzXC9ibG9nXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wN1wvMjAyNTA3MjQtMTUuanBnIiwic2xpZGVzaG93IjoiNTBjNzViNCJ9\" href='https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-15.jpg'><img decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-15-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-15-200x300.jpg 200w, https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-15.jpg 667w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50c75b4\" data-elementor-lightbox-title=\"20250724-18\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDY4LCJ1cmwiOiJodHRwczpcL1wvd2V0cm9uLmVzXC9ibG9nXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wN1wvMjAyNTA3MjQtMTguanBnIiwic2xpZGVzaG93IjoiNTBjNzViNCJ9\" href='https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-18.jpg'><img decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-18-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-18-200x300.jpg 200w, https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-18.jpg 667w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"50c75b4\" data-elementor-lightbox-title=\"20250724-20\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDY5LCJ1cmwiOiJodHRwczpcL1wvd2V0cm9uLmVzXC9ibG9nXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wN1wvMjAyNTA3MjQtMjAuanBnIiwic2xpZGVzaG93IjoiNTBjNzViNCJ9\" href='https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-20.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-20-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-20-200x300.jpg 200w, https:\/\/wetron.es\/blog\/wp-content\/uploads\/2025\/07\/20250724-20.jpg 667w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5661c06 elementor-widget elementor-widget-spacer\" data-id=\"5661c06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec16f33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec16f33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87628d1\" data-id=\"87628d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2101f60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2101f60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5e00b1\" data-id=\"b5e00b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eef331e elementor-widget elementor-widget-spacer\" data-id=\"eef331e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9d6c70 elementor-widget elementor-widget-spacer\" data-id=\"a9d6c70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El pasado jueves 24 de julio celebramos en WETRON nuestro afterwork de verano, una cita pensada para desconectar, disfrutar y reforzar los lazos entre compa\u00f1eros m\u00e1s all\u00e1 del entorno laboral. Tambi\u00e9n un punto de inflexi\u00f3n antes de la famosa \u00abparada de verano\u00bb de muchos de nuestros clientes. Estos se toman un descanso mientras nosotros buscamos implantar las mejoras de las instalaciones de producci\u00f3n que se han planificado y preparado conscientemente. Cuando nuestros clientes vuelven de la parada, las l\u00edneas funcionan de nuevo con normalidad y con las mejoras incorporadas.<\/p>\n","protected":false},"author":2,"featured_media":473,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=464"}],"version-history":[{"count":5,"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/464\/revisions"}],"predecessor-version":[{"id":475,"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/464\/revisions\/475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/media\/473"}],"wp:attachment":[{"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wetron.es\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}